{"id":248,"date":"2009-05-27T21:06:29","date_gmt":"2009-05-28T01:06:29","guid":{"rendered":"http:\/\/oserchanger.com\/blogue_2\/?p=248"},"modified":"2025-11-28T14:41:33","modified_gmt":"2025-11-28T19:41:33","slug":"comment-eviter-problemes-intergenerationnels","status":"publish","type":"post","link":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/","title":{"rendered":"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise?"},"content":{"rendered":"<p>Voici de larges extraits de l\u2019article\u00a0<em>Manager des juniors et\/ou des seniors<\/em> paru sur le site pourseformer.fr.<\/p>\n<p><em>Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise ?\u00a0La question est d\u2019actualit\u00e9 avec d\u2019une part, des jeunes de la g\u00e9n\u00e9ration Y \u00a0que les managers ont parfois peine \u00e0 comprendre. De l\u2019autre, des seniors \u00a0qui non seulement n\u00e9cessiteraient des attentions particuli\u00e8res, mais doivent en plus parfois cohabiter avec les premiers. Une \u00e9quation pas toujours ais\u00e9e \u00e0 r\u00e9soudre.<\/em><\/p>\n<p><span style=\"font-family: Georgia, 'Bitstream Charter', serif; line-height: 24px; font-size: 16px;\"><strong>Ne pas avoir peur de la \u00ab\u00a0g\u00e9n\u00e9ration Y\u00a0\u00bb<\/strong><\/span><\/p>\n<p><em>Premi\u00e8re peur d\u2019un manager prenant la responsabilit\u00e9 d\u2019une \u00e9quipe comptant des juniors\u00a0: celle de leur \u00ab\u00a0non investissement\u00a0\u00bb. Or, la peur est mauvaise conseill\u00e8re, elle peut l\u2019inciter \u00e0 adopter un comportement manag\u00e9rial tr\u00e8s directif, voire agressif (\u00ab\u00a0c\u2019est comme \u00e7\u00e0 et pas autrement\u00a0\u00bb) qui risque de tendre les relations avec l\u2019ensemble de l\u2019\u00e9quipe. Consid\u00e9rer leurs forces potentielles, leurs atouts, avant leurs \u00ab\u00a0faiblesses\u00a0\u00bb et adapter son mode de management en fonction de cette nouvelle donne est pourtant une condition sine qua non de r\u00e9ussite.<\/em><\/p>\n<p><span style=\"font-family: Georgia, 'Bitstream Charter', serif; line-height: 24px; font-size: 16px;\"><strong>Adopter des modes de management adapt\u00e9s. <\/strong><\/span><\/p>\n<p><em>Les jeunes, \u00e0 d\u00e9faut \u00a0d\u2019\u00eatre motiv\u00e9s sur le long terme, peuvent montrer une implication tr\u00e8s forte, \u00e0 condition d\u2019y trouver de l\u2019int\u00e9r\u00eat. Il faut leur proposer une relation gagnant\/gagnant et surtout consid\u00e9rer la mani\u00e8re dont peut se d\u00e9clencher un sentiment d\u2019appartenance. N\u2019oublions pas qu\u2019ils fonctionnent de mani\u00e8re clanique.\u00a0On peut mettre en avant les r\u00e8gles et valeurs de l\u2019entreprise, ou les \u00e9l\u00e9ments qui la symbolisent\u00a0: s\u00e9curit\u00e9, respect, culture produit, savoir-faire\u2026 \u2013 ce qui forge une identit\u00e9 -, et trouver quelqu\u2019un qui leur \u00ab\u00a0montre la voie\u00a0\u00bb. <\/em><\/p>\n<p><span style=\"font-family: Georgia, 'Bitstream Charter', serif; line-height: 24px; font-size: 16px;\"><strong>Veiller \u00e0 l\u2019\u00e9quit\u00e9\u00a0interg\u00e9n\u00e9rationnelle,\u00a0\u00a0cl\u00e9 de l\u2019efficacit\u00e9 des \u00e9quipes.<\/strong><\/span><\/p>\n<p><strong><em>L<span style=\"font-weight: normal;\">es conflits<\/span><\/em> <em><span style=\"font-weight: normal;\"> de g\u00e9n\u00e9ration, au-del\u00e0 de questions de valeurs ou d\u2019attachement \u00e0 l\u2019entreprise, peuvent aussi \u00eatre cr\u00e9\u00e9s par un probl\u00e8me d\u2019\u00e9galit\u00e9 de traitement par l\u2019entreprise. Lorsque les plus anciens constatent que ce sont les plus jeunes qui b\u00e9n\u00e9ficient de primes, d\u2019augmentations, de formations et de promotions, ils se sentent en \u2018\u2019\u00a0sous-\u00e9quit\u00e9\u00a0\u2018\u2019. Quand les plus jeunes consid\u00e8rent que les plus \u00e2g\u00e9s sont mieux r\u00e9mun\u00e9r\u00e9s sans \u00eatre plus productifs ou occupent \u00e0 leur d\u00e9triment les meilleures places dans l\u2019entreprise, ils se sentent \u00e9galement en situation de sous-\u00e9quit\u00e9. Ces sentiments entra\u00eenent des comportements dangereux pour l\u2019efficacit\u00e9 de l\u2019\u00e9quipe. <\/span><\/em><\/strong><\/p>\n<p><span style=\"font-family: Georgia, 'Bitstream Charter', serif; line-height: 24px; font-size: 16px;\"><strong>\u00c9viter la concurrence. <\/strong><\/span><\/p>\n<p><em>R\u00e9partir les fonctions et les missions en consid\u00e9rant l\u2019\u00e2ge et l\u2019exp\u00e9rience<\/em> <em>des salari\u00e9s pour \u00e9viter les conflits et la sensation de concurrence est la voie choisie par des managers qui veillent \u00e0 garder l\u2019\u00e9quilibre.\u00a0\u00ab\u00a0Lorsque j\u2019\u00e9tais manager, \u00e0 quarante ans, j\u2019avais une \u00e9quipe compos\u00e9e de commerciaux, dont l\u2019\u00e2ge allait de 24 ans \u00e0 45 ans. J\u2019ai d\u00e9fini des objectifs et des r\u00f4les diff\u00e9rents selon les profils. Par exemple, le \u2018\u2019\u00a0senior\u00a0\u2018\u2019 \u00e9tait plus impliqu\u00e9 dans du relationnel commercial avec les grands comptes. Il avait pour r\u00f4le de p\u00e9renniser la relation client et de travailler sur de gros projets strat\u00e9giques. Il rassurait le client. Le junior avait lui une fonction de \u00ab\u00a0chasse\u00a0\u00bb et d\u2019extension commerciale. J\u2019\u00e9tais beaucoup plus en coaching et en animation avec eux.\u00a0\u00bb (Fran\u00e7ois Humbert, sp\u00e9cialis\u00e9 dans le recrutement des seniors ).<\/em><\/p>\n<p><span style=\"font-family: Georgia, 'Bitstream Charter', serif; line-height: 24px; font-size: 16px;\"><strong>Les seniors comme piliers<\/strong>.<\/span><\/p>\n<p><strong><em><span style=\"font-weight: normal;\">Face \u00e0 \u00ab\u00a0l\u2019infid\u00e9lit\u00e9\u00a0\u00bb tant regrett\u00e9e des jeunes, les seniors peuvent \u00e9galement jouer un r\u00f4le de soutien. \u00ab\u00a0Un de mes clients avait un souci de turn-over important (plus de 30 %), t\u00e9moigne encore Fran\u00e7ois Humbert. Son probl\u00e8me venait du fait qu\u2019il embauchait des jeunes de deux ans d\u2019exp\u00e9rience, et qu\u2019au bout de deux ou trois ans, ils quittaient la soci\u00e9t\u00e9 par manque d\u2019\u00e9volution de carri\u00e8re et de salaire. En embauchant des seniors, de plus de 45 ans, il a cr\u00e9\u00e9 des \u00ab\u00a0piliers\u00a0\u00bb permettant de solidifier la structure des \u00e9quipes et stabilis\u00e9 son \u00e9quipe. Le senior n\u2019est plus carri\u00e9riste, et souhaite travailler pendant dix ans de mani\u00e8re stable. Il est l\u2019un des fondations de l\u2019entreprise.\u00a0\u00bb<\/span><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conseils pour \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise<\/p>\n","protected":false},"author":9,"featured_media":8068,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[477],"tags":[51,50,1418,188,1417],"class_list":["post-248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-communication","tag-generation-x","tag-generation-y","tag-intergenerationnel","tag-travail-2","tag-travail-en-equipe","post-wrapper","thrv_wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise? - OSERChanger.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise? - OSERChanger.com\" \/>\n<meta property=\"og:description\" content=\"Conseils pour \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/\" \/>\n<meta property=\"og:site_name\" content=\"OSERChanger.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OserChanger\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/OserChanger\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-28T01:06:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-28T19:41:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/public_1200x600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marc Vachon, m.ps.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@marcvachon\" \/>\n<meta name=\"twitter:site\" content=\"@marcvachon\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marc Vachon, m.ps.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/\"},\"author\":{\"name\":\"Marc Vachon, m.ps.\",\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/#\\\/schema\\\/person\\\/636bcde66d5c660902438fec7e0f2fd2\"},\"headline\":\"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise?\",\"datePublished\":\"2009-05-28T01:06:29+00:00\",\"dateModified\":\"2025-11-28T19:41:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/\"},\"wordCount\":719,\"publisher\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/#\\\/schema\\\/person\\\/636bcde66d5c660902438fec7e0f2fd2\"},\"image\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/wp-content\\\/uploads\\\/public_1200x600.jpg\",\"keywords\":[\"G\u00e9n\u00e9ration X\",\"G\u00e9n\u00e9ration Y\",\"interg\u00e9n\u00e9rationnel\",\"travail\",\"travail en \u00e9quipe\"],\"articleSection\":[\"Relations &amp; communication\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/\",\"url\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/\",\"name\":\"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise? - OSERChanger.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/wp-content\\\/uploads\\\/public_1200x600.jpg\",\"datePublished\":\"2009-05-28T01:06:29+00:00\",\"dateModified\":\"2025-11-28T19:41:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/wp-content\\\/uploads\\\/public_1200x600.jpg\",\"contentUrl\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/wp-content\\\/uploads\\\/public_1200x600.jpg\",\"width\":1200,\"height\":602},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/2009\\\/05\\\/27\\\/comment-eviter-problemes-intergenerationnels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/#website\",\"url\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/\",\"name\":\"OSERChanger.com\",\"description\":\"Personne ne peut diriger le vent, mais on peut apprendre \u00e0 ajuster nos voiles\",\"publisher\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/#\\\/schema\\\/person\\\/636bcde66d5c660902438fec7e0f2fd2\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/#\\\/schema\\\/person\\\/636bcde66d5c660902438fec7e0f2fd2\",\"name\":\"Marc Vachon, m.ps.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/wp-content\\\/uploads\\\/Marc_ress_pro_300_300-150x1501.jpg\",\"url\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/wp-content\\\/uploads\\\/Marc_ress_pro_300_300-150x1501.jpg\",\"contentUrl\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/wp-content\\\/uploads\\\/Marc_ress_pro_300_300-150x1501.jpg\",\"width\":150,\"height\":150,\"caption\":\"Marc Vachon, m.ps.\"},\"logo\":{\"@id\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/wp-content\\\/uploads\\\/Marc_ress_pro_300_300-150x1501.jpg\"},\"description\":\"Marc Vachon est passionn\u00e9 par la recherche de moyens pratiques pour \u00eatre heureux et traverser activement les changements. Il a \u0153uvr\u00e9 comme enseignant, psychologue, conf\u00e9rencier et formateur. Il est l'auteur de Oser changer. Mettre le cap sur ses r\u00eaves et de Lacher prise. Prendre de l\u2019altitude.\",\"sameAs\":[\"http:\\\/\\\/oserchanger.com\",\"https:\\\/\\\/www.facebook.com\\\/OserChanger\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marc-vachon-m-ps-10988311\",\"https:\\\/\\\/www.pinterest.ca\\\/oserchanger\\\/\",\"https:\\\/\\\/x.com\\\/marcvachon\"],\"url\":\"https:\\\/\\\/oserchanger.com\\\/blogue_2\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise? - OSERChanger.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/","og_locale":"fr_CA","og_type":"article","og_title":"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise? - OSERChanger.com","og_description":"Conseils pour \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise","og_url":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/","og_site_name":"OSERChanger.com","article_publisher":"https:\/\/www.facebook.com\/OserChanger","article_author":"https:\/\/www.facebook.com\/OserChanger","article_published_time":"2009-05-28T01:06:29+00:00","article_modified_time":"2025-11-28T19:41:33+00:00","og_image":[{"width":1200,"height":602,"url":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/public_1200x600.jpg","type":"image\/jpeg"}],"author":"Marc Vachon, m.ps.","twitter_card":"summary_large_image","twitter_creator":"@marcvachon","twitter_site":"@marcvachon","twitter_misc":{"\u00c9crit par":"Marc Vachon, m.ps.","Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/#article","isPartOf":{"@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/"},"author":{"name":"Marc Vachon, m.ps.","@id":"https:\/\/oserchanger.com\/blogue_2\/#\/schema\/person\/636bcde66d5c660902438fec7e0f2fd2"},"headline":"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise?","datePublished":"2009-05-28T01:06:29+00:00","dateModified":"2025-11-28T19:41:33+00:00","mainEntityOfPage":{"@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/"},"wordCount":719,"publisher":{"@id":"https:\/\/oserchanger.com\/blogue_2\/#\/schema\/person\/636bcde66d5c660902438fec7e0f2fd2"},"image":{"@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/#primaryimage"},"thumbnailUrl":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/public_1200x600.jpg","keywords":["G\u00e9n\u00e9ration X","G\u00e9n\u00e9ration Y","interg\u00e9n\u00e9rationnel","travail","travail en \u00e9quipe"],"articleSection":["Relations &amp; communication"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/","url":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/","name":"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise? - OSERChanger.com","isPartOf":{"@id":"https:\/\/oserchanger.com\/blogue_2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/#primaryimage"},"image":{"@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/#primaryimage"},"thumbnailUrl":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/public_1200x600.jpg","datePublished":"2009-05-28T01:06:29+00:00","dateModified":"2025-11-28T19:41:33+00:00","breadcrumb":{"@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/#primaryimage","url":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/public_1200x600.jpg","contentUrl":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/public_1200x600.jpg","width":1200,"height":602},{"@type":"BreadcrumbList","@id":"https:\/\/oserchanger.com\/blogue_2\/2009\/05\/27\/comment-eviter-problemes-intergenerationnels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/oserchanger.com\/blogue_2\/"},{"@type":"ListItem","position":2,"name":"Comment \u00e9viter les probl\u00e8mes interg\u00e9n\u00e9rationnels dans l\u2019entreprise?"}]},{"@type":"WebSite","@id":"https:\/\/oserchanger.com\/blogue_2\/#website","url":"https:\/\/oserchanger.com\/blogue_2\/","name":"OSERChanger.com","description":"Personne ne peut diriger le vent, mais on peut apprendre \u00e0 ajuster nos voiles","publisher":{"@id":"https:\/\/oserchanger.com\/blogue_2\/#\/schema\/person\/636bcde66d5c660902438fec7e0f2fd2"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oserchanger.com\/blogue_2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":["Person","Organization"],"@id":"https:\/\/oserchanger.com\/blogue_2\/#\/schema\/person\/636bcde66d5c660902438fec7e0f2fd2","name":"Marc Vachon, m.ps.","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/Marc_ress_pro_300_300-150x1501.jpg","url":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/Marc_ress_pro_300_300-150x1501.jpg","contentUrl":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/Marc_ress_pro_300_300-150x1501.jpg","width":150,"height":150,"caption":"Marc Vachon, m.ps."},"logo":{"@id":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/Marc_ress_pro_300_300-150x1501.jpg"},"description":"Marc Vachon est passionn\u00e9 par la recherche de moyens pratiques pour \u00eatre heureux et traverser activement les changements. Il a \u0153uvr\u00e9 comme enseignant, psychologue, conf\u00e9rencier et formateur. Il est l'auteur de Oser changer. Mettre le cap sur ses r\u00eaves et de Lacher prise. Prendre de l\u2019altitude.","sameAs":["http:\/\/oserchanger.com","https:\/\/www.facebook.com\/OserChanger","https:\/\/www.linkedin.com\/in\/marc-vachon-m-ps-10988311","https:\/\/www.pinterest.ca\/oserchanger\/","https:\/\/x.com\/marcvachon"],"url":"https:\/\/oserchanger.com\/blogue_2\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/oserchanger.com\/blogue_2\/wp-content\/uploads\/public_1200x600.jpg","_links":{"self":[{"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/posts\/248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/comments?post=248"}],"version-history":[{"count":1,"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/posts\/248\/revisions"}],"predecessor-version":[{"id":33503,"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/posts\/248\/revisions\/33503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/media\/8068"}],"wp:attachment":[{"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/media?parent=248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/categories?post=248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oserchanger.com\/blogue_2\/wp-json\/wp\/v2\/tags?post=248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}